{"id":94606,"date":"2026-03-27T18:09:03","date_gmt":"2026-03-27T17:09:03","guid":{"rendered":"https:\/\/infotorrent.es\/?p=94606"},"modified":"2026-03-27T18:09:06","modified_gmt":"2026-03-27T17:09:06","slug":"torrent-reunix-mes-de-mil-persones-en-la-gran-jornada-de-convivencia-de-la-setmana-de-la-dona-amb-marxa-reivindicativa-paelles-solidaries-i-mascleta","status":"publish","type":"post","link":"https:\/\/infotorrent.es\/ca\/alcaldia-2\/torrent-reunix-mes-de-mil-persones-en-la-gran-jornada-de-convivencia-de-la-setmana-de-la-dona-amb-marxa-reivindicativa-paelles-solidaries-i-mascleta\/","title":{"rendered":"Torrent reunix m\u00e9s de mil persones en la gran jornada de conviv\u00e8ncia de la Setmana de la Dona amb marxa reivindicativa, paelles solid\u00e0ries i masclet\u00e0"},"content":{"rendered":"\n<p><strong>La jornada, celebrada en l&#8217;\u00c0gora del Parc Central, va aconseguir recaptar 2.600 euros per a l&#8217;Associaci\u00f3 Espanyola Contra el C\u00e0ncer<\/strong><\/p>\n\n\n\n<p>Torrent ha celebrat hui amb gran participaci\u00f3 ciutadana la jornada de conviv\u00e8ncia de la Setmana de la Dona 2026, una cita que havia sigut ajornada setmanes arrere a causa dels avisos meteorol\u00f2gics per pluja i que finalment s&#8217;ha desenrotllat amb un ambient festiu, participatiu i reivindicatiu en l&#8217;\u00c0gora del Parc Central, que ha comptat amb l&#8217;assist\u00e8ncia de l&#8217;alcaldessa Amparo Folgado, la regidora de Dona i responsable de Casa de la Dona, Amparo Chust, al costat de membres de l&#8217;equip de govern i del consistori.<\/p>\n\n\n\n<p>M\u00e9s de mil persones han participat al llarg de la jornada en les diferents activitats programades, que han incl\u00f2s la marxa reivindicativa per la igualtat acompanyada per la batucada d&#8217;ADISTO, la tradicional jornada de paelles solid\u00e0ries, m\u00fasica en directe i el tret d&#8217;una gran masclet\u00e0 en honor a la dona, posant el fermall final a una jornada que ha reunit associacions, col\u00b7lectius i ve\u00efns de la ciutat.<\/p>\n\n\n\n<p><strong>Paelles solid\u00e0ries i m\u00fasica en directe per a compartir una jornada festiva<\/strong><\/p>\n\n\n\n<p>Un dels moments centrals del dia ha sigut la jornada de paelles solid\u00e0ries, que ha tornat a convertir l&#8217;\u00c0gora del Parc Central en un espai de trobada entre associacions i ciutadania.<\/p>\n\n\n\n<p>Els tiquets solidaris, amb un preu simb\u00f2lic de 3 euros, han perm\u00e9s recaptar 2.600 euros, que es destinaran \u00edntegrament a l&#8217;Associaci\u00f3 Espanyola Contra el C\u00e0ncer (AECC), refor\u00e7ant el car\u00e0cter solidari d&#8217;esta activitat.<\/p>\n\n\n\n<p>Durant el menjar, l&#8217;ambient festiu ha estat amenitzat pel duo Brillantina, que ha oferit m\u00fasica en directe amb un repertori variat que ha incl\u00f2s pasdobles, txa-txa-txas, temes populars i can\u00e7ons plenes de ritme, que han fet ballar i disfrutar als assistents durant tota la jornada en un ambient marcat pels riures, la conviv\u00e8ncia i la participaci\u00f3.<\/p>\n\n\n\n<p><strong>Una masclet\u00e0 en honor a la dona<\/strong><\/p>\n\n\n\n<p>Despr\u00e9s del menjar, la jornada ha culminat amb un dels moments m\u00e9s esperats: el tret de la gran masclet\u00e0 en honor a la dona, que ha congregat a nombrosos ve\u00efns a l&#8217;entorn del Parc Central.<\/p>\n\n\n\n<p>L&#8217;espectacle pirot\u00e8cnic ha sigut disparat per Pirot\u00e8cnia Aitana, de B\u00e8lgida, la responsable de la qual \u00e9s Isabel Benavente, en un gest que tamb\u00e9 ha volgut visibilitzar el paper de la dona en sectors tradicionalment masculinizados com el de la pirot\u00e8cnia.<\/p>\n\n\n\n<p>El tret ha comptat amb la pres\u00e8ncia de les Falleres Majors de Torrent 2026, Andrea Adelantado i Sara Mag\u00e1n i les seues Corts de Hionor, que van voler sumar-se a esta jornada de conviv\u00e8ncia i celebraci\u00f3.<\/p>\n\n\n\n<p><strong>Una jornada que recupera un dels actes m\u00e9s participatius de la Setmana de la Dona<\/strong><\/p>\n\n\n\n<p>L&#8217;alcaldessa de Torrent, Amparo Folgado, ha valorat molt positivament la gran participaci\u00f3 registrada durant la jornada, <strong>\u201chui Torrent ha tornat a demostrar que quan es tracta de conviure, compartir i reivindicar la igualtat, la nostra ciutat respon sempre amb una gran participaci\u00f3. Esta jornada de paelles i conviv\u00e8ncia \u00e9s un dels actes m\u00e9s estimats de la Setmana de la Dona i ens alegra enormement haver pogut celebrar-la finalment amb tanta gent gaudint i participant\u201d<\/strong>, ha assenyalat l&#8217;alcaldessa.<\/p>\n\n\n\n<p>Folgado tamb\u00e9 ha destacat el car\u00e0cter solidari i social de l&#8217;esdeveniment, <strong>\u201ca m\u00e9s de ser una jornada festiva i participativa, tamb\u00e9 t\u00e9 un important component solidari. La recaptaci\u00f3 destinada a l&#8217;Associaci\u00f3 Espanyola Contra el C\u00e0ncer demostra una vegada m\u00e9s el comprom\u00eds i la sensibilitat dels ve\u00efns de Torrent amb les causes socials\u201d<\/strong>, ha afegit.<\/p>\n\n\n\n<p>Per part seua, la regidora de Dona i responsable de la Casa de la Dona, Amparo Chust, ha subratllat l&#8217;ambient de conviv\u00e8ncia que s&#8217;ha viscut durant tota la jornada, <strong>\u201cles paelles de la Setmana de la Dona s\u00f3n un s\u00edmbol de trobada entre associacions, col\u00b7lectius i ve\u00efns. \u00c9s una jornada que mescla reivindicaci\u00f3, solidaritat i celebraci\u00f3, i que cada any reunix a centenars de persones entorn dels valors d&#8217;igualtat i conviv\u00e8ncia\u201d<\/strong>, ha explicat la regidora.<\/p>\n\n\n\n<p>Chust tamb\u00e9 ha volgut agrair la implicaci\u00f3 de totes les persones que han fet possible la celebraci\u00f3 de l&#8217;esdeveniment, <strong>\u201cvolem agrair la participaci\u00f3 de totes les associacions, voluntaris, patrocinadors i ve\u00efns que han contribu\u00eft al fet que esta jornada haja sigut un \u00e8xit. Despr\u00e9s de l&#8217;ajornament per motius meteorol\u00f2gics, hui hem pogut disfrutar de la jornada com mereix: amb participaci\u00f3, m\u00fasica, conviv\u00e8ncia i molta alegria\u201d<\/strong>, ha concl\u00f2s.<\/p>\n\n\n\n<p>Amb la celebraci\u00f3 d&#8217;esta jornada, l&#8217;Ajuntament de Torrent culmina els actes de conviv\u00e8ncia de la Setmana de la Dona 2026, una programaci\u00f3 impulsada des de la Casa de la Dona que durant diverses setmanes ha promogut activitats culturals, educatives, socials i participatives per a visibilitzar el paper de les dones i continuar avan\u00e7ant cap a una societat m\u00e9s igualit\u00e0ria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/1-29-1024x682.jpg\" alt=\"\" class=\"wp-image-94607\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/1-29-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/1-29-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/1-29-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/1-29-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/1-29.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94613\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-30-1024x683.jpg\" alt=\"\" class=\"wp-image-94613\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-30-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-30-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-30-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-30-1536x1024.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-30.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94615\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-18-1024x683.jpg\" alt=\"\" class=\"wp-image-94615\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-18-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-18-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-18-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-18-1536x1024.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-18.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94620\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/17-4-1024x683.jpg\" alt=\"\" class=\"wp-image-94620\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/17-4-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/17-4-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/17-4-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/17-4.jpg 1065w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"94622\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-29-1024x682.jpg\" alt=\"\" class=\"wp-image-94622\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-29-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-29-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-29-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-29-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-29.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"94626\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/3-30-1024x682.jpg\" alt=\"\" class=\"wp-image-94626\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/3-30-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/3-30-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/3-30-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/3-30-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/3-30.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"94628\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/20-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-94628\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/20-1-1024x682.jpeg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/20-1-300x200.jpeg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/20-1-768x512.jpeg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/20-1-1536x1023.jpeg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/20-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-31-1024x682.jpg\" alt=\"\" class=\"wp-image-94630\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-31-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-31-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-31-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-31-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/4-31.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94636\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-31-1024x683.jpg\" alt=\"\" class=\"wp-image-94636\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-31-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-31-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-31-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-31-1536x1024.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/2-31.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94634\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/9-21-1024x683.jpg\" alt=\"\" class=\"wp-image-94634\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/9-21-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/9-21-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/9-21-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/9-21.jpg 1065w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"94638\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/12-9-1024x683.jpg\" alt=\"\" class=\"wp-image-94638\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/12-9-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/12-9-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/12-9-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/12-9.jpg 1065w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/13-7-1024x683.jpg\" alt=\"\" class=\"wp-image-94640\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/13-7-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/13-7-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/13-7-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/13-7.jpg 1065w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"94644\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/7-26-1024x682.jpg\" alt=\"\" class=\"wp-image-94644\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/7-26-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/7-26-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/7-26-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/7-26-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/7-26.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"94646\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-19-1024x682.jpg\" alt=\"\" class=\"wp-image-94646\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-19-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-19-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-19-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-19-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/8-19.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/6-24-1024x682.jpg\" alt=\"\" class=\"wp-image-94648\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/6-24-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/6-24-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/6-24-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/6-24-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2026\/03\/6-24.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La jornada, celebrada en l&#8217;\u00c0gora del Parc Central, va aconseguir recaptar 2.600 euros per a l&#8217;Associaci\u00f3 Espanyola Contra el C\u00e0ncer Torrent ha celebrat hui amb gran participaci\u00f3 ciutadana la jornada de conviv\u00e8ncia de la Setmana de la Dona 2026, una cita que havia sigut ajornada setmanes arrere a causa dels avisos meteorol\u00f2gics per pluja i [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":94617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[141,1190,1162,1232],"tags":[],"class_list":["post-94606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alcaldia-2","category-ayuntamiento-de-torrent-ca","category-casa-de-la-dona-ca","category-dona-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/94606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/comments?post=94606"}],"version-history":[{"count":1,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/94606\/revisions"}],"predecessor-version":[{"id":94650,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/94606\/revisions\/94650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/media\/94617"}],"wp:attachment":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/media?parent=94606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/categories?post=94606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/tags?post=94606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}