{"id":84032,"date":"2025-07-24T12:21:25","date_gmt":"2025-07-24T10:21:25","guid":{"rendered":"https:\/\/infotorrent.es\/?p=84032"},"modified":"2025-07-24T12:24:50","modified_gmt":"2025-07-24T10:24:50","slug":"torrent-es-prepara-per-a-un-cap-de-setmana-musical-i-humoristic-en-les-seues-festes-patronals","status":"publish","type":"post","link":"https:\/\/infotorrent.es\/ca\/festes-i-tradicions-2\/torrent-es-prepara-per-a-un-cap-de-setmana-musical-i-humoristic-en-les-seues-festes-patronals\/","title":{"rendered":"Torrent es prepara per a un cap de setmana musical i humor\u00edstic en les seues festes patronals"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Les festes patronals de Torrent combinen espectacles per a tots els gustos en diferents places de la ciutat<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">Tota la programaci\u00f3 festiva de la ciutat pot veure&#8217;s en la web&nbsp;<a href=\"http:\/\/torrent.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">torrent.es<\/a><\/h4>\n\n\n\n<p>La ciutat de Torrent es prepara per a viure un intens cap de setmana ple de m\u00fasica i humor, emmarcat en les festes patronals en honor als sants Abd\u00f3 i Sen\u00e9n. Del divendres 25 al diumenge 27 de juliol, els barris del municipi seran escenari d\u2019una programaci\u00f3 variada, pensada per a tots els p\u00fablics i amb una clara aposta per la dinamitzaci\u00f3 cultural en les places i espais oberts.<\/p>\n\n\n\n<p>Un dels grans atractius d\u2019enguany \u00e9s el retorn del Circuit de Monologuistes, que recorrer\u00e0 diferents punts de la ciutat amb actuacions de c\u00f2mics de primer nivell com Piter Pardo, Maxi Rangel, \u00c1lex Mart\u00ednez, Manu Baeza i Sr. Corrales, que actuaran en quatre places de la ciutat. L\u2019humor es combina aix\u00ed amb els concerts i tributs musicals, consolidant una f\u00f3rmula que ja ha tingut gran \u00e8xit en edicions anteriors.<\/p>\n\n\n\n<p><strong>Divendres de ball, tributs i humor<\/strong><\/p>\n\n\n\n<p>El divendres 25 de juliol comen\u00e7ar\u00e0 amb una cita molt esperada pels majors del barri de l\u2019Eixample: l\u2019\u00faltim ball de la temporada a l\u2019Espai Sant Gregori, que tindr\u00e0 lloc de 18.00 a 21.00 h. Esta activitat, habitual tots els divendres, s\u2019acomiadar\u00e0 fins al setembre, deixant un agradable sabor de boca a aquells que cada setmana acudeixen a disfrutar del sal\u00f3 de ball del barri.<\/p>\n\n\n\n<p>A la nit, la programaci\u00f3 es repartir\u00e0 entre diferents escenaris. A la pla\u00e7a de l\u2019Esgl\u00e9sia, a les 22.00 h, es retr\u00e0 homenatge a una de les grans figures de l\u2019humor i el teatre espanyol amb el musical \u201cSin M\u00e1s\u201d, dedicat a la inigualable Lina Morgan. A la mateixa hora, per\u00f2 en altres places, comen\u00e7ar\u00e0 l\u2019activitat del Circuit de Monologuistes: Piter Pardo i Maxi Rangel actuaran a El Vedat (cantonada amb el carrer Font de Sant Llu\u00eds), mentre que \u00c1lex Mart\u00ednez i Manu Baeza ho faran a l\u2019aparcament del carrer Benem\u00e8rita Gu\u00e0rdia Civil.<\/p>\n\n\n\n<p>A m\u00e9s, la m\u00fasica en directe omplir\u00e0 l\u2019ambient amb tres potents tributs. A la pla\u00e7a de la Llibertat, el grup \u201cCam\u00e9lame\u201d far\u00e0 vibrar el p\u00fablic amb un tribut a Camela, mentre que a la pla\u00e7a Pedro Iturralde, \u201cLa Otra Oreja\u201d recordar\u00e0 els grans \u00e8xits de La Oreja de Van Gogh.<\/p>\n\n\n\n<p><strong>Dissabte amb m\u00e9s m\u00fasica, humor i ball en fam\u00edlia<\/strong><\/p>\n\n\n\n<p>El dissabte 26 de juliol continuar\u00e0 amb una programaci\u00f3 festiva i familiar. A les 19.00 h, la pla\u00e7a Uni\u00f3 Musical acollir\u00e0 el Gran Ball del Dia dels Iaios, una cita entranyable en qu\u00e8 es retr\u00e0 homenatge als majors amb l\u2019actuaci\u00f3 en directe del grup \u00a1Oh la la!, en un ambient carregat d\u2019alegria intergeneracional.<\/p>\n\n\n\n<p>A la nit, la m\u00fasica tornar\u00e0 a ser protagonista. A la pla\u00e7a de l\u2019Esgl\u00e9sia, a les 22.00 h, se celebrar\u00e0 un emotiu tribut al D\u00fao Din\u00e1mico sota el t\u00edtol \u201cResistir\u00e9\u201d. A les 22.30 h, el p\u00fablic podr\u00e0 triar entre diverses propostes: el grup \u201cVoy a pas\u00e1rmelo bien\u201d portar\u00e0 l\u2019esperit dels Hombres G a la pla\u00e7a de la Llibertat; el musical infantil \u201cOgro, Tribut a Shrek\u201d es presentar\u00e0 a la pla\u00e7a Pedro Iturralde, i el Circuit de Monologuistes continuar\u00e0 el seu recorregut amb dues actuacions simult\u00e0nies: \u00c1lex Mart\u00ednez i Maxi Rangel a la pla\u00e7a Fra Antonio Panes, i Piter Pardo i Sr. Corrales al carrer Mestre Lorenzo Fuertes J\u00falvez (junt a Comare Pilar Mart\u00ed).<\/p>\n\n\n\n<p>La jornada culminar\u00e0 a mitjanit amb el tradicional Ball a la Torre, organitzat per la Federaci\u00f3 de Moros i Cristians de Torrent (FMCT).<\/p>\n\n\n\n<p><strong>Diumenge musical i faller<\/strong><\/p>\n\n\n\n<p>La nit posar\u00e0 el colof\u00f3 a este cap de setmana ple de m\u00fasica i art. A les 22.00 h, la pla\u00e7a de l\u2019Esgl\u00e9sia acollir\u00e0 el concert \u201cUn Viatge per la M\u00fasica\u201d amb Jaime i Coral, mentre que la pla\u00e7a de la Llibertat celebrar\u00e0 el Festival de Playbacks Fallers, una de les activitats m\u00e9s participatives del calendari festiu. Finalment, a la pla\u00e7a Pedro Iturralde, el musical \u201cAlegr\u00eda\u201d posar\u00e0 la nota m\u00e0gica a una programaci\u00f3 que ha portat la cultura a tots els racons de Torrent.<\/p>\n\n\n\n<p>La ciutat demostra aix\u00ed, una vegada m\u00e9s, el seu comprom\u00eds amb unes festes obertes, inclusives i descentralitzades, on cada barri es convertix en punt de trobada per a compartir alegria, m\u00fasica i humor.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"84029\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.11_1175f0b0-1024x682.jpg\" alt=\"\" class=\"wp-image-84029\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.11_1175f0b0-1024x682.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.11_1175f0b0-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.11_1175f0b0-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.11_1175f0b0-1536x1023.jpg 1536w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.11_1175f0b0.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"84027\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.24_bcc5b849-1024x768.jpg\" alt=\"\" class=\"wp-image-84027\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.24_bcc5b849-1024x768.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.24_bcc5b849-300x225.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.24_bcc5b849-768x576.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-24-a-las-12.16.24_bcc5b849.jpg 1182w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Les festes patronals de Torrent combinen espectacles per a tots els gustos en diferents places de la ciutat Tota la programaci\u00f3 festiva de la ciutat pot veure&#8217;s en la web&nbsp;torrent.es La ciutat de Torrent es prepara per a viure un intens cap de setmana ple de m\u00fasica i humor, emmarcat en les festes patronals en [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":84027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1190,156],"tags":[],"class_list":["post-84032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-de-torrent-ca","category-festes-i-tradicions-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/84032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/comments?post=84032"}],"version-history":[{"count":1,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/84032\/revisions"}],"predecessor-version":[{"id":84034,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/84032\/revisions\/84034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/media\/84027"}],"wp:attachment":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/media?parent=84032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/categories?post=84032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/tags?post=84032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}