{"id":51276,"date":"2022-08-02T09:07:52","date_gmt":"2022-08-02T09:07:52","guid":{"rendered":"https:\/\/infotorrent.es\/?p=51276"},"modified":"2022-08-02T09:07:54","modified_gmt":"2022-08-02T09:07:54","slug":"torrent-posa-el-fermall-dor-a-les-seues-festes-patronals","status":"publish","type":"post","link":"https:\/\/infotorrent.es\/ca\/cultura-ca\/torrent-posa-el-fermall-dor-a-les-seues-festes-patronals\/","title":{"rendered":"Torrent posa el fermall d&#8217;or a les seues festes patronals"},"content":{"rendered":"\n<p><strong>Torrent, 01\/08\/2022<\/strong>. Un any m\u00e9s, la ciutat de Torrent s&#8217;acomiada de les seues festes patronals despr\u00e9s d&#8217;un intens mes de juliol carregat d&#8217;activitats i esdeveniments per a tots els p\u00fablics, el qual va arribar a la seua fi dissabte passat amb la celebraci\u00f3 de la solemne missa major a l&#8217;esgl\u00e9sia de l&#8217;Asunci\u00f3n i la posterior process\u00f3 en honor als Sants Patrons,\u00a0 Abd\u00f3n i\u00a0Sen\u00e9n, que va ser seguida per una\u00a0masclet\u00e0 nocturna al costat de la pla\u00e7a de la Uni\u00f3 Musical, en la qual es van disparar 98 kg de p\u00f3lvora. Despr\u00e9s de l&#8217;espectacle de foc i color, es va celebrar una\u00a0picaeta per als all\u00ed presents, tancant, aix\u00ed, l&#8217;\u00faltima vetlada de les festes patronals 2022.<br><br>A m\u00e9s, de destacar \u201cel gran acolliment i participaci\u00f3 que han tingut les activitats festives desenvolupades durant tot el mes\u201d, el regidor de Festes, Jos\u00e9 Pascual Martinez, ha volgut mostrar el seu agra\u00efment \u201da les quasi 500 persones de Protecci\u00f3 Civil, Policia Local, FCC, Brigada d&#8217;Obres i de les \u00e0rees de Cultura i Festes de l&#8217;Ajuntament de Torrent que han contribu\u00eft al fet que els 85 actes i activitats d&#8217;aquestes festes patronals foren un \u00e8xit\u201d, destaca el regidor de Festes, Jos\u00e9 Pascual Mart\u00ednez.<br><br><br><strong>Antonio Carmona i fam\u00edlia<\/strong><br>El mateix dissabte a la nit, la pla\u00e7a de la Llibertat va acollir l&#8217;\u00faltim concert de les festes patronals de Torrent, el qual va arribar de la m\u00e0 del cantaor flamenc Antonio Carmona, qui va fer les del\u00edcies del p\u00fablic congregat en l&#8217;abarrotada pla\u00e7a amb el seu espectacle \u2018Antonio Carmona i fam\u00edlia\u2019.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1365\" data-id=\"51258\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-1.jpg\" alt=\"\" class=\"wp-image-51258\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-1.jpg 2048w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-1-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-1-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-1-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1365\" height=\"2048\" data-id=\"51260\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-2.jpg\" alt=\"\" class=\"wp-image-51260\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-2.jpg 1365w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-2-200x300.jpg 200w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-2-683x1024.jpg 683w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-2-768x1152.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Procesion-2-1024x1536.jpg 1024w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2048\" height=\"1365\" data-id=\"51264\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_4.jpg\" alt=\"\" class=\"wp-image-51264\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_4.jpg 2048w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_4-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_4-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_4-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_4-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" data-id=\"51266\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_5.jpg\" alt=\"\" class=\"wp-image-51266\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_5.jpg 2048w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_5-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_5-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_5-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_5-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" data-id=\"51268\" src=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_1-1.jpg\" alt=\"\" class=\"wp-image-51268\" srcset=\"https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_1-1.jpg 2048w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_1-1-300x200.jpg 300w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_1-1-1024x683.jpg 1024w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_1-1-768x512.jpg 768w, https:\/\/infotorrent.es\/wp-content\/uploads\/2022\/08\/Carmona_1-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Torrent, 01\/08\/2022. Un any m\u00e9s, la ciutat de Torrent s&#8217;acomiada de les seues festes patronals despr\u00e9s d&#8217;un intens mes de juliol carregat d&#8217;activitats i esdeveniments per a tots els p\u00fablics, el qual va arribar a la seua fi dissabte passat amb la celebraci\u00f3 de la solemne missa major a l&#8217;esgl\u00e9sia de l&#8217;Asunci\u00f3n i la posterior [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":51278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[163],"tags":[],"class_list":["post-51276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/51276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/comments?post=51276"}],"version-history":[{"count":1,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/51276\/revisions"}],"predecessor-version":[{"id":51277,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/posts\/51276\/revisions\/51277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/media\/51278"}],"wp:attachment":[{"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/media?parent=51276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/categories?post=51276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infotorrent.es\/ca\/wp-json\/wp\/v2\/tags?post=51276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}